{"id":1877,"count":2,"description":"","link":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/","name":"CLOSED SANDAL\r\n","slug":"mens-closed-sandal","taxonomy":"product_cat","parent":1702,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CLOSED SANDAL  - Zak Shoes<\/title>\n<meta name=\"description\" content=\"CLOSED SANDAL  - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CLOSED SANDAL  - Zak Shoes\" \/>\n<meta property=\"og:description\" content=\"CLOSED SANDAL  - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/\" \/>\n<meta property=\"og:site_name\" content=\"Zak Shoes\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product-category\\\/men\\\/mens-closed-sandal\\\/\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product-category\\\/men\\\/mens-closed-sandal\\\/\",\"name\":\"CLOSED SANDAL - Zak Shoes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#website\"},\"description\":\"CLOSED SANDAL - Zak Shoes CLOSED SANDAL - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product-category\\\/men\\\/mens-closed-sandal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product-category\\\/men\\\/mens-closed-sandal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Men\",\"item\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product-category\\\/men\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CLOSED SANDAL\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\",\"name\":\"Zak Shoes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zak.shoes\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#organization\",\"name\":\"ZAK Shoes\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/logo2.png\",\"contentUrl\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/logo2.png\",\"width\":331,\"height\":130,\"caption\":\"ZAK Shoes\"},\"image\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zakshoes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zakshoes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CLOSED SANDAL  - Zak Shoes","description":"CLOSED SANDAL  - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/","og_locale":"en_US","og_type":"article","og_title":"CLOSED SANDAL  - Zak Shoes","og_description":"CLOSED SANDAL  - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","og_url":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/","og_site_name":"Zak Shoes","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/","url":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/","name":"CLOSED SANDAL - Zak Shoes","isPartOf":{"@id":"https:\/\/zak.shoes\/en\/#website"},"description":"CLOSED SANDAL - Zak Shoes CLOSED SANDAL - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes CLOSED SANDAL - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","breadcrumb":{"@id":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zak.shoes\/en\/product-category\/men\/mens-closed-sandal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zak.shoes\/en\/"},{"@type":"ListItem","position":2,"name":"Men","item":"https:\/\/zak.shoes\/en\/product-category\/men\/"},{"@type":"ListItem","position":3,"name":"CLOSED SANDAL"}]},{"@type":"WebSite","@id":"https:\/\/zak.shoes\/en\/#website","url":"https:\/\/zak.shoes\/en\/","name":"Zak Shoes","description":"","publisher":{"@id":"https:\/\/zak.shoes\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zak.shoes\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zak.shoes\/en\/#organization","name":"ZAK Shoes","url":"https:\/\/zak.shoes\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zak.shoes\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zak.shoes\/wp-content\/uploads\/logo2.png","contentUrl":"https:\/\/zak.shoes\/wp-content\/uploads\/logo2.png","width":331,"height":130,"caption":"ZAK Shoes"},"image":{"@id":"https:\/\/zak.shoes\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zakshoes\/","https:\/\/www.instagram.com\/zakshoes\/"]}]}},"_links":{"self":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_cat\/1877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_cat\/1702"}],"wp:post_type":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product?product_cat=1877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}