{"id":418659,"date":"2026-04-16T00:00:00","date_gmt":"2026-04-14T00:00:00","guid":{"rendered":"\/?p=418659"},"modified":"2026-04-16T00:00:00","modified_gmt":"2026-04-16T00:00:00","slug":"sd31010","status":"publish","type":"product","link":"https:\/\/zak.shoes\/en\/product\/sd31010\/","title":{"rendered":"WOMEN PUMPS\r\n PU\r\n PRC"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":362168,"template":"","meta":[],"pwb-brand":[1559],"product_brand":[],"product_cat":[1569],"product_tag":[],"class_list":{"0":"post-418659","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"pwb-brand-blondie","7":"product_cat-women-pumps","8":"pa_color-black","9":"pa_color-burdeos","10":"pa_size-1502","11":"pa_size-1503","12":"pa_size-1504","13":"pa_size-1498","14":"pa_size-1491","15":"pa_size-1492","17":"first","18":"instock","19":"taxable","20":"shipping-taxable","21":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>WOMEN PUMPS  PU  PRC  - Zak Shoes<\/title>\n<meta name=\"description\" content=\"WOMEN PUMPS  PU  PRC  - Zak Shoes WOMEN PUMPS  PU  PRC  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zak.shoes\/en\/product\/sd31010\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"WOMEN PUMPS  PU  PRC  - Zak Shoes\" \/>\n<meta property=\"og:description\" content=\"WOMEN PUMPS  PU  PRC  - Zak Shoes WOMEN PUMPS  PU  PRC  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zak.shoes\/en\/product\/sd31010\/\" \/>\n<meta property=\"og:site_name\" content=\"Zak Shoes\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zakshoes\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-16T00:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zak.shoes\/wp-content\/uploads\/products\/SD31010-3.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/\",\"name\":\"WOMEN PUMPS PU PRC - Zak Shoes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/products\\\/SD31010-3.jpg\",\"datePublished\":\"2026-04-14T00:00:00+00:00\",\"dateModified\":\"2026-04-16T00:00:00+00:00\",\"description\":\"WOMEN PUMPS PU PRC - Zak Shoes WOMEN PUMPS PU PRC - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/products\\\/SD31010-3.jpg\",\"contentUrl\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/products\\\/SD31010-3.jpg\",\"width\":800,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/product\\\/sd31010\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collection\",\"item\":\"https:\\\/\\\/zak.shoes\\\/en\\\/collection\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"WOMEN PUMPS PU PRC\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\",\"name\":\"Zak Shoes\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zak.shoes\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#organization\",\"name\":\"ZAK Shoes\",\"url\":\"https:\\\/\\\/zak.shoes\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/logo2.png\",\"contentUrl\":\"https:\\\/\\\/zak.shoes\\\/wp-content\\\/uploads\\\/logo2.png\",\"width\":331,\"height\":130,\"caption\":\"ZAK Shoes\"},\"image\":{\"@id\":\"https:\\\/\\\/zak.shoes\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zakshoes\\\/\",\"https:\\\/\\\/www.instagram.com\\\/zakshoes\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"WOMEN PUMPS  PU  PRC  - Zak Shoes","description":"WOMEN PUMPS  PU  PRC  - Zak Shoes WOMEN PUMPS  PU  PRC  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zak.shoes\/en\/product\/sd31010\/","og_locale":"en_US","og_type":"article","og_title":"WOMEN PUMPS  PU  PRC  - Zak Shoes","og_description":"WOMEN PUMPS  PU  PRC  - Zak Shoes WOMEN PUMPS  PU  PRC  - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","og_url":"https:\/\/zak.shoes\/en\/product\/sd31010\/","og_site_name":"Zak Shoes","article_publisher":"https:\/\/www.facebook.com\/zakshoes\/","article_modified_time":"2026-04-16T00:00:00+00:00","og_image":[{"width":800,"height":800,"url":"https:\/\/zak.shoes\/wp-content\/uploads\/products\/SD31010-3.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/","url":"https:\/\/zak.shoes\/en\/product\/sd31010\/","name":"WOMEN PUMPS PU PRC - Zak Shoes","isPartOf":{"@id":"https:\/\/zak.shoes\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/#primaryimage"},"image":{"@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/#primaryimage"},"thumbnailUrl":"https:\/\/zak.shoes\/wp-content\/uploads\/products\/SD31010-3.jpg","datePublished":"2026-04-14T00:00:00+00:00","dateModified":"2026-04-16T00:00:00+00:00","description":"WOMEN PUMPS PU PRC - Zak Shoes WOMEN PUMPS PU PRC - Zak Shoes - Zak Shoes - Zak Shoes - Zak Shoes","breadcrumb":{"@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zak.shoes\/en\/product\/sd31010\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/#primaryimage","url":"https:\/\/zak.shoes\/wp-content\/uploads\/products\/SD31010-3.jpg","contentUrl":"https:\/\/zak.shoes\/wp-content\/uploads\/products\/SD31010-3.jpg","width":800,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/zak.shoes\/en\/product\/sd31010\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zak.shoes\/en\/"},{"@type":"ListItem","position":2,"name":"Collection","item":"https:\/\/zak.shoes\/en\/collection\/"},{"@type":"ListItem","position":3,"name":"WOMEN PUMPS PU PRC"}]},{"@type":"WebSite","@id":"https:\/\/zak.shoes\/en\/#website","url":"https:\/\/zak.shoes\/en\/","name":"Zak Shoes","description":"","publisher":{"@id":"https:\/\/zak.shoes\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zak.shoes\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/zak.shoes\/en\/#organization","name":"ZAK Shoes","url":"https:\/\/zak.shoes\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zak.shoes\/en\/#\/schema\/logo\/image\/","url":"https:\/\/zak.shoes\/wp-content\/uploads\/logo2.png","contentUrl":"https:\/\/zak.shoes\/wp-content\/uploads\/logo2.png","width":331,"height":130,"caption":"ZAK Shoes"},"image":{"@id":"https:\/\/zak.shoes\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zakshoes\/","https:\/\/www.instagram.com\/zakshoes\/"]}]}},"brands":[{"id":1559,"name":"Blondie","slug":"blondie"}],"_links":{"self":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product\/418659","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/media\/362168"}],"wp:attachment":[{"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/media?parent=418659"}],"wp:term":[{"taxonomy":"pwb-brand","embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/pwb-brand?post=418659"},{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_brand?post=418659"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_cat?post=418659"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/zak.shoes\/en\/wp-json\/wp\/v2\/product_tag?post=418659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}